{"id":26128,"date":"2025-11-18T01:49:09","date_gmt":"2025-11-18T00:49:09","guid":{"rendered":"http:\/\/www.associationdemarie.org\/blog\/?p=26128"},"modified":"2025-11-04T07:51:22","modified_gmt":"2025-11-04T06:51:22","slug":"le-salut-est-arrive","status":"publish","type":"post","link":"https:\/\/www.associationdemarie.org\/blog\/le-salut-est-arrive\/","title":{"rendered":"\u00ab Le salut est arriv\u00e9 ! \u00bb"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2025\/11\/18-11.jpeg\" alt=\"\" class=\"wp-image-26129\" srcset=\"https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2025\/11\/18-11.jpeg 400w, https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2025\/11\/18-11-150x150.jpeg 150w, https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2025\/11\/18-11-300x300.jpeg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure><\/div>\n\n\n\n<p> \u00ab\u00a0S\u2019il l\u00e2che les eaux, elles retourneront la terre.\u00a0\u00bb (Jb 12,15 Vg) Que peut, en effet, repr\u00e9senter la terre, sinon le p\u00e9cheur, sur qui a \u00e9t\u00e9 port\u00e9 ce jugement\u00a0: \u00ab\u00a0Tu es terre et tu deviendras terre\u00a0\u00bb (Gn 3,19)\u00a0? Voil\u00e0 pourquoi la terre demeure immobile quand le p\u00e9cheur d\u00e9daigne d\u2019ob\u00e9ir aux commandements du Seigneur, quand il redresse sa nuque orgueilleuse et qu\u2019il ferme les yeux de son \u00e2me \u00e0 la lumi\u00e8re de la V\u00e9rit\u00e9.<\/p>\n\n\n\n<p> Mais il est \u00e9crit\u00a0: \u00ab\u00a0Ses pieds se sont arr\u00eat\u00e9s et la terre a \u00e9t\u00e9 \u00e9branl\u00e9e\u00a0\u00bb (Ha 3,6), parce que, si la v\u00e9rit\u00e9 se fixe en un c\u0153ur, l\u2019immobilit\u00e9 de l\u2019\u00e2me est secou\u00e9e\u00a0; aussi, que la gr\u00e2ce du Saint Esprit par un don d\u2019en-haut se r\u00e9pande en elle avec la parole du pr\u00e9dicateur, voil\u00e0 la terre retourn\u00e9e, parce que l\u2019\u00e2me endurcie dans le p\u00e9ch\u00e9 perd l\u2019ent\u00eatement de son immobilit\u00e9, transform\u00e9e au point de se soumettre alors en pleurant aux commandements du Seigneur tout autant qu\u2019hier dans sa superbe elle redressait en face du Seigneur la nuque de son c\u0153ur. Il n\u2019est que de voir la terre d\u2019un c\u0153ur d\u2019homme baign\u00e9e des eaux de la gr\u00e2ce\u00a0: elle supporte maintenant sans d\u00e9plaisir les outrages qu\u2019elle s\u2019acharnait hier \u00e0 infliger\u00a0; maintenant elle distribue ses propres biens, elle mortifie sa chair par l\u2019abstinence, elle qui hier, rassasi\u00e9e de chair, se laissait aller aux charmes mortels des turpitudes\u00a0; maintenant elle ch\u00e9rit m\u00eame ceux qui l\u2019aimaient.<\/p>\n\n\n\n<p>  Ainsi, quand dans une \u00e2me d\u2019homme le don divin a \u00e9t\u00e9 r\u00e9pandu et qu\u2019elle en vient \u00e0 agir \u00e0 l\u2019encontre de ce qu\u2019elle avait l\u2019habitude de faire, la terre est retourn\u00e9e\u00a0: vers le bas a \u00e9t\u00e9 rejet\u00e9e celle qui hier \u00e9tait en saillie et s\u2019est \u00e9lev\u00e9e vers le haut la face qui hier s\u2019enfon\u00e7ait dans les profondeurs.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Saint Gr\u00e9goire le Grand (v. 540-604)<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0S\u2019il l\u00e2che les eaux, elles retourneront la terre.\u00a0\u00bb (Jb 12,15 Vg) Que peut, en effet, repr\u00e9senter la terre, sinon le p\u00e9cheur, sur qui a \u00e9t\u00e9 port\u00e9 ce jugement\u00a0: \u00ab\u00a0Tu es terre et tu deviendras terre\u00a0\u00bb (Gn 3,19)\u00a0? Voil\u00e0 pourquoi la terre demeure immobile quand le p\u00e9cheur d\u00e9daigne d\u2019ob\u00e9ir aux commandements du Seigneur, quand il redresse [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,1261],"tags":[949,1488],"class_list":["post-26128","post","type-post","status-publish","format-standard","hentry","category-ecritures","category-enseignement-2","tag-salut","tag-st-gregoire-le-grand"],"_links":{"self":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts\/26128","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/comments?post=26128"}],"version-history":[{"count":1,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts\/26128\/revisions"}],"predecessor-version":[{"id":26130,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts\/26128\/revisions\/26130"}],"wp:attachment":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/media?parent=26128"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/categories?post=26128"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/tags?post=26128"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}