{"id":25756,"date":"2025-07-24T01:06:25","date_gmt":"2025-07-24T00:06:25","guid":{"rendered":"http:\/\/www.associationdemarie.org\/blog\/?p=25756"},"modified":"2025-07-11T06:09:16","modified_gmt":"2025-07-11T05:09:16","slug":"heureux-vos-yeux-parce-quils-voient-et-vos-oreilles-parce-quelles-entendent","status":"publish","type":"post","link":"https:\/\/www.associationdemarie.org\/blog\/heureux-vos-yeux-parce-quils-voient-et-vos-oreilles-parce-quelles-entendent\/","title":{"rendered":"\u00ab Heureux vos yeux parce qu&rsquo;ils voient, et vos oreilles parce qu&rsquo;elles entendent. \u00bb"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"807\" src=\"https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2025\/07\/24-07-1024x807.png\" alt=\"\" class=\"wp-image-25757\" srcset=\"https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2025\/07\/24-07-1024x807.png 1024w, https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2025\/07\/24-07-300x237.png 300w, https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2025\/07\/24-07-768x605.png 768w, https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2025\/07\/24-07.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Un arbre abattu, coup\u00e9 m\u00eame sur le pied, repousse et refleurit ; et un homme abattu ne revivra pas ? Les semences moissonn\u00e9es reposent, dorment dans les greniers et revivent au printemps ; et l&rsquo;homme moissonn\u00e9, jet\u00e9 dans les greniers de la mort, ne revivra pas ? Un bourgeon de vigne, une branche coup\u00e9e et transplant\u00e9e, se ravivent et portent des fruits ; et l&rsquo;homme pour qui tout a \u00e9t\u00e9 cr\u00e9\u00e9, une fois tomb\u00e9 ne pourra pas se relever ?\u2026<\/p>\n\n\n\n<p>Contemplez donc ce qui se passe autour de vous. M\u00e9ditez sur le tableau de ce vaste univers. Je s\u00e8me du bl\u00e9 ou toute autre graine; il tombe et meurt, il pourrit et ne peut plus servir \u00e0 la nourriture de l&rsquo;homme. Mais de sa pourriture il rena\u00eet, il s&rsquo;\u00e9l\u00e8ve, il se multiplie. Or pour qui a-t-il \u00e9t\u00e9 cr\u00e9\u00e9 ? N&rsquo;est-ce pas pour notre usage ? Ce n&rsquo;est pas pour elles-m\u00eames que toutes ces semences sont sorties du n\u00e9ant. Donc ce qui a \u00e9t\u00e9 cr\u00e9\u00e9 pour nous meurt et rena\u00eet, et nous, pour qui ce prodige s&rsquo;op\u00e8re tous les jours, notre mort serait sans r\u00e9veil ?<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Saint Cyrille de J\u00e9rusalem (313-350)<\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Un arbre abattu, coup\u00e9 m\u00eame sur le pied, repousse et refleurit ; et un homme abattu ne revivra pas ? Les semences moissonn\u00e9es reposent, dorment dans les greniers et revivent au printemps ; et l&rsquo;homme moissonn\u00e9, jet\u00e9 dans les greniers de la mort, ne revivra pas ? Un bourgeon de vigne, une branche coup\u00e9e et [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,1261,16],"tags":[269,516,1499],"class_list":["post-25756","post","type-post","status-publish","format-standard","hentry","category-ecritures","category-enseignement-2","category-jardins-de-la-bible","tag-creation","tag-jardin","tag-st-cyrille-de-jerusalem"],"_links":{"self":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts\/25756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/comments?post=25756"}],"version-history":[{"count":1,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts\/25756\/revisions"}],"predecessor-version":[{"id":25758,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts\/25756\/revisions\/25758"}],"wp:attachment":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/media?parent=25756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/categories?post=25756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/tags?post=25756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}