{"id":15952,"date":"2018-02-17T01:15:35","date_gmt":"2018-02-17T00:15:35","guid":{"rendered":"http:\/\/www.associationdemarie.org\/blog\/?p=15952"},"modified":"2018-02-02T06:17:08","modified_gmt":"2018-02-02T05:17:08","slug":"le-samedi-apres-les-cendres-2","status":"publish","type":"post","link":"https:\/\/www.associationdemarie.org\/blog\/le-samedi-apres-les-cendres-2\/","title":{"rendered":"Le samedi apr\u00e8s les Cendres"},"content":{"rendered":"<p><a href=\"https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2018\/02\/MosesAndTheBrassSerpent-765x1024.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-15953\" src=\"https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2018\/02\/MosesAndTheBrassSerpent-765x1024.jpg\" alt=\"MosesAndTheBrassSerpent-765x1024\" width=\"394\" height=\"527\" srcset=\"https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2018\/02\/MosesAndTheBrassSerpent-765x1024.jpg 765w, https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2018\/02\/MosesAndTheBrassSerpent-765x1024-224x300.jpg 224w\" sizes=\"auto, (max-width: 394px) 100vw, 394px\" \/><\/a><\/p>\n<p>Le temps du Car\u00eame rappelle les quarante ans qu&rsquo;Isra\u00ebl a pass\u00e9s dans le d\u00e9sert quand il \u00e9tait en marche vers la Terre Promise. Pendant cette p\u00e9riode, le peuple a appris ce que signifiait vivre sous la tente, sans domicile fixe, dans une absence totale de s\u00e9curit\u00e9. Bien des fois, il a \u00e9t\u00e9 tent\u00e9 de retourner en \u00c9gypte\u00a0: l\u00e0, au moins, il \u00e9tait s\u00fbr d&rsquo;avoir \u00e0 manger, m\u00eame si c&rsquo;\u00e9tait une nourriture d&rsquo;esclaves. Dans la pr\u00e9carit\u00e9 du d\u00e9sert, c&rsquo;est Dieu lui-m\u00eame qui a fourni l&rsquo;eau et la nourriture \u00e0 son peuple et qui l&rsquo;a prot\u00e9g\u00e9 de tous les dangers. Ainsi l&rsquo;exp\u00e9rience de d\u00e9pendre totalement de Dieu s&rsquo;est transform\u00e9e pour les H\u00e9breux en marche pour se lib\u00e9rer de l&rsquo;esclavage et de l&rsquo;idol\u00e2trie des biens mat\u00e9riels.<\/p>\n<p>Le temps du Car\u00eame aide les croyants \u00e0 revivre, dans un effort de purification personnelle, ce m\u00eame itin\u00e9raire spirituel en prenant conscience de la pauvret\u00e9 et de la pr\u00e9carit\u00e9 de l&rsquo;existence, et en red\u00e9couvrant l&rsquo;intervention providentielle du Seigneur, qui invite \u00e0 ouvrir les yeux sur les besoins de nos fr\u00e8res les plus n\u00e9cessiteux. De cette fa\u00e7on, le Car\u00eame devient aussi le temps de la solidarit\u00e9 avec les individus et les peuples des nombreuses parties du monde qui se trouvent en situation pr\u00e9caire&#8230;<\/p>\n<p>C&rsquo;est de l&rsquo;amour de Dieu que le chr\u00e9tien apprend \u00e0 secourir celui qui est dans le besoin&#8230;; il existe en effet une dimension plus \u00e9lev\u00e9e, indiqu\u00e9e par l&rsquo;exemple du Christ lui-m\u00eame\u00a0: \u00ab\u00a0Le Fils de l&rsquo;homme n&rsquo;a pas d&rsquo;endroit o\u00f9 reposer sa t\u00eate\u00a0\u00bb (Mt 8,20). Il voulait exprimer ainsi sa disponibilit\u00e9 totale envers son P\u00e8re du ciel, dont il voulait accomplir la volont\u00e9 sans se laisser entraver par la possession de biens terrestres&#8230; Le Christ nous pr\u00e9c\u00e8de sur cette route. Sa pr\u00e9sence est une force et un encouragement\u00a0: il nous rend libres et nous fait devenir des t\u00e9moins de son amour.<\/p>\n<p>Saint Jean-Paul II (1920-2005), pape<br \/>\n<i>Message pour le Car\u00eame 1997 (trad. \u00a9 copyright Libreria Editrice Vaticana rev.)<\/i><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le temps du Car\u00eame rappelle les quarante ans qu&rsquo;Isra\u00ebl a pass\u00e9s dans le d\u00e9sert quand il \u00e9tait en marche vers la Terre Promise. Pendant cette p\u00e9riode, le peuple a appris ce que signifiait vivre sous la tente, sans domicile fixe, dans une absence totale de s\u00e9curit\u00e9. Bien des fois, il a \u00e9t\u00e9 tent\u00e9 de retourner [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1482,13,1261],"tags":[184,288,683,1253,1134],"class_list":["post-15952","post","type-post","status-publish","format-standard","hentry","category-careme-2018","category-ecritures","category-enseignement-2","tag-careme","tag-desert","tag-moise","tag-st-jean-paul-2","tag-tentation"],"_links":{"self":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts\/15952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/comments?post=15952"}],"version-history":[{"count":2,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts\/15952\/revisions"}],"predecessor-version":[{"id":15955,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts\/15952\/revisions\/15955"}],"wp:attachment":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/media?parent=15952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/categories?post=15952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/tags?post=15952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}