{"id":14903,"date":"2017-06-05T01:11:23","date_gmt":"2017-06-05T00:11:23","guid":{"rendered":"http:\/\/www.associationdemarie.org\/blog\/?p=14903"},"modified":"2017-05-22T05:13:19","modified_gmt":"2017-05-22T04:13:19","slug":"le-maitre-de-la-vigne","status":"publish","type":"post","link":"https:\/\/www.associationdemarie.org\/blog\/le-maitre-de-la-vigne\/","title":{"rendered":"Le ma\u00eetre de la vigne"},"content":{"rendered":"<p><a href=\"https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2017\/05\/croix.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-14904\" src=\"https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2017\/05\/croix.jpg\" alt=\"croix\" width=\"302\" height=\"417\" srcset=\"https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2017\/05\/croix.jpg 223w, https:\/\/www.associationdemarie.org\/blog\/wp-content\/uploads\/2017\/05\/croix-217x300.jpg 217w\" sizes=\"auto, (max-width: 302px) 100vw, 302px\" \/><\/a><\/p>\n<p>[Sainte Catherine a entendu Dieu lui dire]\u00a0: \u00ab\u00a0Toute cr\u00e9ature dou\u00e9e de raison poss\u00e8de en elle-m\u00eame une vigne, qui est la vigne de son \u00e2me. C&rsquo;est la volont\u00e9, par le libre arbitre, qui est l&rsquo;ouvrier de cette vigne durant le temps de la vie\u00a0; pass\u00e9 ce temps, elle n&rsquo;y peut plus faire aucun travail ni bon ni mauvais, mais pendant la vie, elle peut cultiver sa vigne dans laquelle je l&rsquo;ai envoy\u00e9e. Cet ouvrier de l&rsquo;\u00e2me a re\u00e7u de moi une telle force qu&rsquo;il n&rsquo;est ni d\u00e9mon ni autre cr\u00e9ature qui puisse la lui enlever, s&rsquo;il s&rsquo;y oppose. C&rsquo;est dans le bapt\u00eame qu&rsquo;il a re\u00e7u cette force et en m\u00eame temps le glaive de l&rsquo;amour de la vertu et de la haine du p\u00e9ch\u00e9. C&rsquo;est pour cet amour et cette haine, pour l&rsquo;amour de vous et en haine du p\u00e9ch\u00e9, qu&rsquo;est mort mon Fils unique, en r\u00e9pandant pour vous tout son sang. Et c&rsquo;est cet amour de la vertu et cette haine du p\u00e9ch\u00e9 que vous trouvez dans le saint bapt\u00eame qui vous rend la vie par la force de son sang&#8230;<\/p>\n<p>\u00ab\u00a0Arrachez donc les ronces des p\u00e9ch\u00e9s mortels et plantez des vertus&#8230;, ayez la contrition, le d\u00e9go\u00fbt du p\u00e9ch\u00e9 et l&rsquo;amour de la vertu\u00a0; alors vous recevrez les fruits du sang de mon Fils. Vous ne pourrez pas les recevoir si vous ne vous disposez pas \u00e0 devenir de bons sarments unis au cep de la vigne, mon Fils, qui a dit\u00a0: \u00ab\u00a0Moi, je suis la vraie vigne, mon P\u00e8re est le vigneron, et vous, les sarments\u00a0\u00bb (Jn 15,1.5).<\/p>\n<p>\u00ab\u00a0Telle est la v\u00e9rit\u00e9. C&rsquo;est bien moi qui suis le vigneron, puisque toute chose qui poss\u00e8de l&rsquo;\u00eatre est venue et vient de moi. Ma puissance est insondable et par ma puissance et ma force je gouverne tout l&rsquo;univers, si bien que rien n&rsquo;est fait ni ordonn\u00e9 en dehors de moi. Oui, je suis le vigneron\u00a0; c&rsquo;est moi qui ai plant\u00e9 la vraie vigne, mon Fils unique, dans la terre de votre humanit\u00e9 pour que vous, les sarments unis \u00e0 cette vigne, vous portiez des fruits.\u00a0\u00bb<\/p>\n<p>Sainte Catherine de Sienne (1347-1380), tertiaire dominicaine, docteur de l&rsquo;\u00c9glise, copatronne de l&rsquo;Europe<br \/>\n<i>Le Dialogue, 23 (trad. cf Hurtaud, et Guigues, Seuil 1953)<\/i><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[Sainte Catherine a entendu Dieu lui dire]\u00a0: \u00ab\u00a0Toute cr\u00e9ature dou\u00e9e de raison poss\u00e8de en elle-m\u00eame une vigne, qui est la vigne de son \u00e2me. C&rsquo;est la volont\u00e9, par le libre arbitre, qui est l&rsquo;ouvrier de cette vigne durant le temps de la vie\u00a0; pass\u00e9 ce temps, elle n&rsquo;y peut plus faire aucun travail ni bon [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,13,1261,16],"tags":[1089,1190],"class_list":["post-14903","post","type-post","status-publish","format-standard","hentry","category-liturgique","category-ecritures","category-enseignement-2","category-jardins-de-la-bible","tag-ste-catherine-de-sienne","tag-vigne"],"_links":{"self":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts\/14903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/comments?post=14903"}],"version-history":[{"count":1,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts\/14903\/revisions"}],"predecessor-version":[{"id":14905,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/posts\/14903\/revisions\/14905"}],"wp:attachment":[{"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/media?parent=14903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/categories?post=14903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.associationdemarie.org\/blog\/wp-json\/wp\/v2\/tags?post=14903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}